{"id":358,"count":8,"description":"","link":"https:\/\/oper-graz.buehnen-graz.com\/en\/mitwirkende\/nanine-linning\/","name":"Nanine Linning","slug":"nanine-linning","taxonomy":"th-contributor","meta":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Nanine Linning | Oper Graz<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nanine Linning | Oper Graz\" \/>\n<meta property=\"og:url\" content=\"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/\" \/>\n<meta property=\"og:site_name\" content=\"Oper Graz\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/mitwirkende\\\/nanine-linning\\\/\",\"url\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/mitwirkende\\\/nanine-linning\\\/\",\"name\":\"Nanine Linning | Oper Graz\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/mitwirkende\\\/nanine-linning\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/mitwirkende\\\/nanine-linning\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nanine Linning\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#website\",\"url\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/\",\"name\":\"Oper Graz\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#organization\",\"name\":\"Oper Graz\",\"url\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-GB\",\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/OperGraz_Logo_600.png\",\"contentUrl\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/wp-content\\\/uploads\\\/2023\\\/07\\\/OperGraz_Logo_600.png\",\"width\":600,\"height\":145,\"caption\":\"Oper Graz\"},\"image\":{\"@id\":\"https:\\\/\\\/oper-graz.buehnen-graz.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/OperGraz\",\"https:\\\/\\\/www.youtube.com\\\/@opergraz2001\",\"https:\\\/\\\/www.instagram.com\\\/oper_graz\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Nanine Linning | Oper Graz","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/","og_locale":"en_US","og_type":"article","og_title":"Nanine Linning | Oper Graz","og_url":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/","og_site_name":"Oper Graz","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/","url":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/","name":"Nanine Linning | Oper Graz","isPartOf":{"@id":"https:\/\/oper-graz.buehnen-graz.com\/#website"},"breadcrumb":{"@id":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/oper-graz.buehnen-graz.com\/mitwirkende\/nanine-linning\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/oper-graz.buehnen-graz.com\/en\/"},{"@type":"ListItem","position":2,"name":"Nanine Linning"}]},{"@type":"WebSite","@id":"https:\/\/oper-graz.buehnen-graz.com\/#website","url":"https:\/\/oper-graz.buehnen-graz.com\/","name":"Oper Graz","description":"","publisher":{"@id":"https:\/\/oper-graz.buehnen-graz.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/oper-graz.buehnen-graz.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"},{"@type":"Organization","@id":"https:\/\/oper-graz.buehnen-graz.com\/#organization","name":"Oper Graz","url":"https:\/\/oper-graz.buehnen-graz.com\/","logo":{"@type":"ImageObject","inLanguage":"en-GB","@id":"https:\/\/oper-graz.buehnen-graz.com\/#\/schema\/logo\/image\/","url":"https:\/\/oper-graz.buehnen-graz.com\/wp-content\/uploads\/2023\/07\/OperGraz_Logo_600.png","contentUrl":"https:\/\/oper-graz.buehnen-graz.com\/wp-content\/uploads\/2023\/07\/OperGraz_Logo_600.png","width":600,"height":145,"caption":"Oper Graz"},"image":{"@id":"https:\/\/oper-graz.buehnen-graz.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/OperGraz","https:\/\/www.youtube.com\/@opergraz2001","https:\/\/www.instagram.com\/oper_graz\/"]}]}},"_links":{"self":[{"href":"https:\/\/oper-graz.buehnen-graz.com\/en\/wp-json\/wp\/v2\/contributor\/358","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/oper-graz.buehnen-graz.com\/en\/wp-json\/wp\/v2\/contributor"}],"about":[{"href":"https:\/\/oper-graz.buehnen-graz.com\/en\/wp-json\/wp\/v2\/taxonomies\/th-contributor"}],"wp:post_type":[{"href":"https:\/\/oper-graz.buehnen-graz.com\/en\/wp-json\/wp\/v2\/events?contributor=358"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}